{"id":7571,"date":"2023-03-06T11:11:38","date_gmt":"2023-03-06T10:11:38","guid":{"rendered":"https:\/\/www.kiosquesdumonde.net\/wordpress\/?p=7571"},"modified":"2023-03-06T11:11:38","modified_gmt":"2023-03-06T10:11:38","slug":"kiosque-a-musique-a-luneville-france","status":"publish","type":"post","link":"https:\/\/www.kiosquesdumonde.net\/wordpress\/kiosque-a-musique-a-luneville-france\/","title":{"rendered":"Kiosque \u00e0 musique \u00e0 Lun\u00e9ville (France)"},"content":{"rendered":"<div style=\"width: 625px; border: 3px solid #bff0c3; padding: 50px 25px;\">\n<p style=\"padding-left: 30px; text-align: justify;\">Dans le parc du ch\u00e2teau \u00e0 Lun\u00e9ville se trouve un kiosque \u00e0 musique octogonal.<\/p>\n<div id=\"attachment_7574\" style=\"width: 635px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-7574\" class=\"size-large wp-image-7574\" src=\"https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/01-Luneville-CP-850x548.jpg\" alt=\"\" width=\"625\" height=\"403\" srcset=\"https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/01-Luneville-CP-850x548.jpg 850w, https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/01-Luneville-CP-300x193.jpg 300w, https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/01-Luneville-CP-768x495.jpg 768w, https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/01-Luneville-CP-624x402.jpg 624w, https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/01-Luneville-CP.jpg 858w\" sizes=\"auto, (max-width: 625px) 100vw, 625px\" \/><p id=\"caption-attachment-7574\" class=\"wp-caption-text\">CP Magasins r\u00e9unis de Lun\u00e9ville, \u00c9diteurs<\/p><\/div>\n<p>Il a \u00e9t\u00e9 construit en 1880 par la Soci\u00e9t\u00e9 anonyme de m\u00e9tallurgie artistique de Saint-Sauveur-les-Arras.<\/p>\n<div id=\"attachment_7575\" style=\"width: 635px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-7575\" class=\"size-large wp-image-7575\" src=\"https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/02-Luneville-850x641.jpg\" alt=\"\" width=\"625\" height=\"471\" srcset=\"https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/02-Luneville-850x641.jpg 850w, https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/02-Luneville-300x226.jpg 300w, https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/02-Luneville-768x579.jpg 768w, https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/02-Luneville-624x471.jpg 624w, https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/02-Luneville.jpg 1322w\" sizes=\"auto, (max-width: 625px) 100vw, 625px\" \/><p id=\"caption-attachment-7575\" class=\"wp-caption-text\">\u00a9 Patricia G. juin 2013<\/p><\/div>\n<p>Les colonnes sont en fonte et le garde-corps est en fer forg\u00e9.<\/p>\n<div id=\"attachment_7578\" style=\"width: 482px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-7578\" class=\" wp-image-7578\" src=\"https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/05-Luneville-641x850.jpg\" alt=\"\" width=\"472\" height=\"626\" srcset=\"https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/05-Luneville-641x850.jpg 641w, https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/05-Luneville-226x300.jpg 226w, https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/05-Luneville-768x1018.jpg 768w, https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/05-Luneville-624x827.jpg 624w, https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/05-Luneville.jpg 920w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/><p id=\"caption-attachment-7578\" class=\"wp-caption-text\">\u00a9 Patricia G. juin 2013<\/p><\/div>\n<p>Une soumission pour un kiosque m\u00e9tallique fut propos\u00e9e le 1er septembre 1880 par Anthony Jouffray, directeur de la Soci\u00e9t\u00e9 anonyme de m\u00e9tallurgie artistique de Saint-Sauveur-les-Arras, (ancienne usine Grassin-Baledans) pour une somme estim\u00e9e \u00e0 6 494 Francs. [Renseignements re\u00e7us de la mairie.]<br \/>\nElle fut approuv\u00e9e par le Conseil municipal le 19 octobre 1880.<\/p>\n<div id=\"attachment_7577\" style=\"width: 615px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-7577\" class=\" wp-image-7577\" src=\"https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/04-Luneville-850x641.jpg\" alt=\"\" width=\"605\" height=\"456\" srcset=\"https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/04-Luneville-850x641.jpg 850w, https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/04-Luneville-300x226.jpg 300w, https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/04-Luneville-768x579.jpg 768w, https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/04-Luneville-624x471.jpg 624w, https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/04-Luneville.jpg 1220w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/><p id=\"caption-attachment-7577\" class=\"wp-caption-text\">\u00a9 Patricia G. juin 2013<\/p><\/div>\n<p>Des concerts se donnent en \u00e9t\u00e9 dans le Parc des Bosquets.<\/p>\n<div id=\"attachment_7576\" style=\"width: 635px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-7576\" class=\"size-large wp-image-7576\" src=\"https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/03-Luneville-641x850.jpg\" alt=\"\" width=\"625\" height=\"829\" srcset=\"https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/03-Luneville-641x850.jpg 641w, https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/03-Luneville-226x300.jpg 226w, https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/03-Luneville-768x1018.jpg 768w, https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/03-Luneville-624x827.jpg 624w, https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-content\/uploads\/2023\/03\/03-Luneville.jpg 920w\" sizes=\"auto, (max-width: 625px) 100vw, 625px\" \/><p id=\"caption-attachment-7576\" class=\"wp-caption-text\">\u00a9 Patricia G. juin 2013<\/p><\/div>\n<p><iframe loading=\"lazy\" style=\"border: 0;\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m17!1m12!1m3!1d1465.4027397055738!2d6.499648969113443!3d48.59537644577353!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m2!1m1!2zNDjCsDM1JzQzLjQiTiA2wrAzMCcwMi4wIkU!5e1!3m2!1sfr!2sbe!4v1678030639787!5m2!1sfr!2sbe\" width=\"600\" height=\"450\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Merci \u00e0 Patricia pour les photos.<\/p>\n<\/div>\n<div id=\"ConnectiveDocSignExtentionInstalled\" data-extension-version=\"1.0.4\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dans le parc du ch\u00e2teau \u00e0 Lun\u00e9ville se trouve un kiosque \u00e0 musique octogonal. Il a \u00e9t\u00e9 construit en 1880 par la Soci\u00e9t\u00e9 anonyme de m\u00e9tallurgie artistique de Saint-Sauveur-les-Arras. Les colonnes sont en fonte et le garde-corps est en fer forg\u00e9. Une soumission pour un kiosque m\u00e9tallique fut propos\u00e9e le 1er septembre 1880 par Anthony [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[57,496,495],"class_list":["post-7571","post","type-post","status-publish","format-standard","hentry","category-actualites","tag-france","tag-luneville","tag-meutrhe-et-moselle"],"_links":{"self":[{"href":"https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-json\/wp\/v2\/posts\/7571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-json\/wp\/v2\/comments?post=7571"}],"version-history":[{"count":5,"href":"https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-json\/wp\/v2\/posts\/7571\/revisions"}],"predecessor-version":[{"id":7581,"href":"https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-json\/wp\/v2\/posts\/7571\/revisions\/7581"}],"wp:attachment":[{"href":"https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-json\/wp\/v2\/media?parent=7571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-json\/wp\/v2\/categories?post=7571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kiosquesdumonde.net\/wordpress\/wp-json\/wp\/v2\/tags?post=7571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}